{"id":1845,"date":"2025-05-23T10:49:19","date_gmt":"2025-05-23T09:49:19","guid":{"rendered":"https:\/\/pablomor.com\/?post_type=tribe_events&#038;p=1845"},"modified":"2025-05-23T10:49:19","modified_gmt":"2025-05-23T09:49:19","slug":"marimba-y-musica-de-camara-3","status":"publish","type":"tribe_events","link":"https:\/\/pablomor.com\/en\/eventos\/marimba-y-musica-de-camara-3\/","title":{"rendered":"Marimba y M\u00fasica de c\u00e1mara"},"content":{"rendered":"<p>Concierto a d\u00fao de marimbas dentro del ciclo de conciertos de la Fundaci\u00f3n Santa Mar\u00eda con obras de Bach, Katny, S\u00e9journ\u00e9, Dorman.<br \/>\nConrado Moya y Pablo Mor &#8211; marimbas<\/p>","protected":false},"excerpt":{"rendered":"<p>Concierto a d\u00fao de marimbas dentro del ciclo de conciertos de la Fundaci\u00f3n Santa Mar\u00eda con obras de Bach, Katny, S\u00e9journ\u00e9, Dorman. Conrado Moya y Pablo Mor &#8211; marimbas<\/p>","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1845","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marimba y M\u00fasica de c\u00e1mara - Pablo Mor<\/title>\n<meta name=\"description\" content=\"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pablomor.com\/en\/eventos\/marimba-y-musica-de-camara-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marimba y M\u00fasica de c\u00e1mara - Pablo Mor\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pablomor.com\/en\/eventos\/marimba-y-musica-de-camara-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Pablo Mor\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pablo.mor.lillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@pablomrlo\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/\",\"url\":\"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/\",\"name\":\"Marimba y M\u00fasica de c\u00e1mara - Pablo Mor\",\"isPartOf\":{\"@id\":\"https:\/\/pablomor.com\/#website\"},\"datePublished\":\"2025-05-23T09:49:19+00:00\",\"description\":\"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.\",\"breadcrumb\":{\"@id\":\"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pablomor.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\/\/pablomor.com\/eventos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marimba y M\u00fasica de c\u00e1mara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pablomor.com\/#website\",\"url\":\"https:\/\/pablomor.com\/\",\"name\":\"Pablo Mor\",\"description\":\"Marimba &amp; Percusi\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/pablomor.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pablomor.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pablomor.com\/#organization\",\"name\":\"Pablo Mor\",\"url\":\"https:\/\/pablomor.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/pablomor.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pablomor.com\/wp-content\/uploads\/2023\/03\/logo_pablomor.png\",\"contentUrl\":\"https:\/\/pablomor.com\/wp-content\/uploads\/2023\/03\/logo_pablomor.png\",\"width\":500,\"height\":150,\"caption\":\"Pablo Mor\"},\"image\":{\"@id\":\"https:\/\/pablomor.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/pablo.mor.lillo\",\"https:\/\/x.com\/pablomrlo\",\"https:\/\/www.instagram.com\/pablomrlo\/\",\"https:\/\/twitter.com\/pablomrlo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marimba y M\u00fasica de c\u00e1mara - Pablo Mor","description":"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pablomor.com\/en\/eventos\/marimba-y-musica-de-camara-3\/","og_locale":"en_GB","og_type":"article","og_title":"Marimba y M\u00fasica de c\u00e1mara - Pablo Mor","og_description":"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.","og_url":"https:\/\/pablomor.com\/en\/eventos\/marimba-y-musica-de-camara-3\/","og_site_name":"Pablo Mor","article_publisher":"http:\/\/www.facebook.com\/pablo.mor.lillo","twitter_card":"summary_large_image","twitter_site":"@pablomrlo","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/","url":"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/","name":"Marimba y M\u00fasica de c\u00e1mara - Pablo Mor","isPartOf":{"@id":"https:\/\/pablomor.com\/#website"},"datePublished":"2025-05-23T09:49:19+00:00","description":"La Fundaci\u00f3n Santa Mar\u00eda de Albarrac\u00edn presenta un nuevo concierto en la Iglesia-Auditorio de Santa Mar\u00eda el pr\u00f3ximo s\u00e1bado 24 de mayo, a las 19:30 horas, protagonizado por dos destacados int\u00e9rpretes del panorama internacional de la percusi\u00f3n, Conrado Moya y Pablo Mor, en un formato poco habitual y de gran atractivo: un d\u00fao de marimbas.","breadcrumb":{"@id":"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pablomor.com\/eventos\/marimba-y-musica-de-camara-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pablomor.com\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/pablomor.com\/eventos\/"},{"@type":"ListItem","position":3,"name":"Marimba y M\u00fasica de c\u00e1mara"}]},{"@type":"WebSite","@id":"https:\/\/pablomor.com\/#website","url":"https:\/\/pablomor.com\/","name":"Pablo Mor","description":"Marimba &amp; Percusi\u00f3n","publisher":{"@id":"https:\/\/pablomor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pablomor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/pablomor.com\/#organization","name":"Pablo Mor","url":"https:\/\/pablomor.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/pablomor.com\/#\/schema\/logo\/image\/","url":"https:\/\/pablomor.com\/wp-content\/uploads\/2023\/03\/logo_pablomor.png","contentUrl":"https:\/\/pablomor.com\/wp-content\/uploads\/2023\/03\/logo_pablomor.png","width":500,"height":150,"caption":"Pablo Mor"},"image":{"@id":"https:\/\/pablomor.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pablo.mor.lillo","https:\/\/x.com\/pablomrlo","https:\/\/www.instagram.com\/pablomrlo\/","https:\/\/twitter.com\/pablomrlo"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"WePaM_xiESsda","author_link":"https:\/\/pablomor.com\/en\/author\/wepam_xiessda\/"},"uagb_comment_info":0,"uagb_excerpt":"Concierto a d\u00fao de marimbas dentro del ciclo de conciertos de la Fundaci\u00f3n Santa Mar\u00eda con obras de Bach, Katny, S\u00e9journ\u00e9, Dorman. Conrado Moya y Pablo Mor &#8211; marimbas","_links":{"self":[{"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/tribe_events\/1845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/tribe_events\/1845\/revisions"}],"wp:attachment":[{"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/media?parent=1845"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/tags?post=1845"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/pablomor.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=1845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}